{"id":82,"date":"2026-05-14T14:18:11","date_gmt":"2026-05-14T14:18:11","guid":{"rendered":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/?p=82"},"modified":"2026-05-31T11:14:36","modified_gmt":"2026-05-31T11:14:36","slug":"journee-portes-ouvertes-le-13-mai-a-la-fraiserie-de-la-ferlandiere","status":"publish","type":"post","link":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/journee-portes-ouvertes-le-13-mai-a-la-fraiserie-de-la-ferlandiere\/","title":{"rendered":"Journ\u00e9e portes ouvertes le 13 mai \u00e0 la Fraiserie de la Ferlandi\u00e8re"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Notre productrice de farine, p\u00e2tes, flocons d&rsquo;avoine, huiles et lentilles, Les Moissons d&rsquo;Emeline ( <a href=\"https:\/\/www.lesmoissonsdemeline.fr\/\">https:\/\/www.lesmoissonsdemeline.fr\/<\/a> ) sera pr\u00e9sente sur ce march\u00e9 de producteurs samedi, pour celles et ceux qui ne sont pas partis loin d&rsquo;ici\u2026<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"673\" height=\"1024\" src=\"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/a34ce909-cb06-4765-9ec6-0e89836df11c-673x1024.jpg\" alt=\"\" class=\"wp-image-83\" srcset=\"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/a34ce909-cb06-4765-9ec6-0e89836df11c-673x1024.jpg 673w, https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/a34ce909-cb06-4765-9ec6-0e89836df11c-197x300.jpg 197w, https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/a34ce909-cb06-4765-9ec6-0e89836df11c-624x950.jpg 624w, https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/a34ce909-cb06-4765-9ec6-0e89836df11c.jpg 733w\" sizes=\"auto, (max-width: 673px) 100vw, 673px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"1024\" src=\"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/993a004f-b1ff-4b22-94e9-59834be7f202-681x1024.jpg\" alt=\"\" class=\"wp-image-84\" srcset=\"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/993a004f-b1ff-4b22-94e9-59834be7f202-681x1024.jpg 681w, https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/993a004f-b1ff-4b22-94e9-59834be7f202-199x300.jpg 199w, https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/993a004f-b1ff-4b22-94e9-59834be7f202-624x939.jpg 624w, https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-content\/uploads\/2026\/05\/993a004f-b1ff-4b22-94e9-59834be7f202.jpg 740w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Notre productrice de farine, p\u00e2tes, flocons d&rsquo;avoine, huiles et lentilles, Les Moissons d&rsquo;Emeline ( https:\/\/www.lesmoissonsdemeline.fr\/ ) sera pr\u00e9sente sur ce march\u00e9 de producteurs samedi, pour celles et ceux qui ne sont pas partis loin d&rsquo;ici\u2026<\/p>\n","protected":false},"author":1,"featured_media":83,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,29],"tags":[],"class_list":["post-82","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-producteurs","category-sujets-vie-locale"],"_links":{"self":[{"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/posts\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":2,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/posts\/82\/revisions"}],"predecessor-version":[{"id":96,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/posts\/82\/revisions\/96"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/media\/83"}],"wp:attachment":[{"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/media?parent=82"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/categories?post=82"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/tags?post=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}