{"id":100,"date":"2026-05-21T14:42:36","date_gmt":"2026-05-21T14:42:36","guid":{"rendered":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/?p=100"},"modified":"2026-05-31T11:06:43","modified_gmt":"2026-05-31T11:06:43","slug":"pique-nique-stope-campus-ia","status":"publish","type":"post","link":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/pique-nique-stope-campus-ia\/","title":{"rendered":"Pique-nique Stop Campus IA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dimanche, le collectif <strong>\u00ab\u00a0Stop Campus IA\u00a0\u00bb<\/strong> organise un pique-nique convivial tout pr\u00e8s de Fouju.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En pleine enqu\u00eate publique sur ce projet qui pr\u00e9voit d&rsquo;artificialiser 90ha de terres agricoles, pour construire une usine qui battra tous les records de consommation de ressources, associations, agriculteurs, travailleurs du nucl\u00e9aires et citoyens se mobilisent pour informer la population.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au programme : pique-nique partag\u00e9, ateliers et balade naturaliste<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rendez-vous au stade de Champeau d\u00e8s 13h (rue Sarrazin Des maraise, sur la route de St M\u00e9ry).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez faire passer le message \ud83d\ude09<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutes les infos ici : <a href=\"https:\/\/linktr.ee\/stopcampusia\">https:\/\/linktr.ee\/stopcampusia<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour celleux qui vont au pique-nique anti Campus IA :<br>\ud83e\udd6a\ud83d\udccc\ud83d\udce3PIQUE-NIQUE CONTRE CAMPUS IA\ud83d\udc26\u200d\u2b1b\ud83d\udc1e\ud83c\udf1e<br>Rendez-vous dimanche 24 Mai, de 12h30 \u00e0 18h \u00e0 Champeaux<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 Fouju, au coeur de la campagne de Seine et Marne, le projet Campus IA pr\u00e9voit la construction du plus grand parc de data centers d\u2019Europe.<br>Le 24 Mai, \u00e0 l\u2019occasion du Printemps des Luttes Locales, soyons nombreux-ses pour d\u00e9fendre les terres et refuser les data centers et leur monde.<br>Au programme de cette journ\u00e9e : prises de parole, fanfare, balade naturaliste, atelier contre-projet, lecture collective.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83e\udd6aApportez votre pique-nique \u00e0 partager et votre \u00e9co-cup pour les boissons !<br>Pour le go\u00fbter, une surprise vous sera propos\u00e9e sur place (\u00e0 prix libre) : pr\u00e9voyez de la monnaie ! \ud83d\udcb8<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>A tr\u00e8s vite!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dimanche, le collectif \u00ab\u00a0Stop Campus IA\u00a0\u00bb organise un pique-nique convivial tout pr\u00e8s de Fouju. En pleine enqu\u00eate publique sur ce projet qui pr\u00e9voit d&rsquo;artificialiser 90ha de terres agricoles, pour construire une usine qui battra tous les records de consommation de ressources, associations, agriculteurs, travailleurs du nucl\u00e9aires et citoyens se mobilisent pour informer la population. Au programme : pique-nique partag\u00e9, ateliers et balade naturaliste Rendez-vous au stade de Champeau d\u00e8s 13h (rue Sarrazin Des maraise, sur la route de St M\u00e9ry). Vous pouvez faire passer le message \ud83d\ude09 Toutes les infos ici : https:\/\/linktr.ee\/stopcampusia Pour celleux qui vont au pique-nique anti Campus IA :\ud83e\udd6a\ud83d\udccc\ud83d\udce3PIQUE-NIQUE CONTRE CAMPUS IA\ud83d\udc26\u200d\u2b1b\ud83d\udc1e\ud83c\udf1eRendez-vous dimanche 24 Mai, de 12h30 \u00e0 18h \u00e0 Champeaux \u00c0 Fouju, au coeur de la campagne de Seine et Marne, le projet Campus IA pr\u00e9voit la construction du plus grand parc de data centers d\u2019Europe.Le 24 Mai, \u00e0 l\u2019occasion du Printemps des Luttes Locales, soyons nombreux-ses pour d\u00e9fendre les terres et refuser les data centers et leur monde.Au programme de cette journ\u00e9e : prises de parole, fanfare, balade naturaliste, atelier contre-projet, lecture collective. \ud83e\udd6aApportez votre pique-nique \u00e0 partager et votre \u00e9co-cup pour les boissons !Pour le go\u00fbter, une surprise vous sera propos\u00e9e sur place (\u00e0 prix libre) : pr\u00e9voyez de la monnaie ! \ud83d\udcb8 A tr\u00e8s vite!<\/p>\n","protected":false},"author":1,"featured_media":148,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,27,21,26,29],"tags":[],"class_list":["post-100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sujets-agriculture","category-sujets-citoyennete","category-sujets-autour","category-sujets-ecologie","category-sujets-vie-locale"],"_links":{"self":[{"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/posts\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":5,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/posts\/100\/revisions"}],"predecessor-version":[{"id":150,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/posts\/100\/revisions\/150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/media\/148"}],"wp:attachment":[{"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/media?parent=100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/categories?post=100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lespaniersdupuitsgodichon.org\/blog\/wp-json\/wp\/v2\/tags?post=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}